{"id":55065,"date":"2023-10-27T11:37:39","date_gmt":"2023-10-27T15:37:39","guid":{"rendered":"http:\/\/debateplural.com\/inicio\/?p=55065"},"modified":"2023-10-27T11:37:40","modified_gmt":"2023-10-27T15:37:40","slug":"esta-el-capitalismo-en-fase-terminal","status":"publish","type":"post","link":"https:\/\/debateplural.net\/site\/2023\/10\/27\/esta-el-capitalismo-en-fase-terminal\/","title":{"rendered":"\u00bfEst\u00e1 el capitalismo en fase terminal?"},"content":{"rendered":"\n<p>Doug Henwood (Sin Permiso, 27-10-23)<\/p>\n\n\n\n<p>Un debate entre Seth Ackerman y Aaron Benanav sobre el pron\u00f3stico del capitalismo: \u00bfEst\u00e1 experimentando el tipo de estancamiento a largo plazo que muchos marxistas han considerado durante mucho tiempo como su destino? \u00bfQu\u00e9 significa esta respuesta para la estrategia pol\u00edtica socialista actual? Entrevista realizada por Doug Henwood.<\/p>\n\n\n\n<p>Durante las dos \u00faltimas d\u00e9cadas,&nbsp;<em>New Left Review (NLR)<\/em>&nbsp;ha estado publicando art\u00edculos que diagnostican que el sistema capitalista sufre un estancamiento a largo plazo, un exceso de capacidad cr\u00f3nico, una rentabilidad decreciente y un crecimiento lento.<\/p>\n\n\n\n<p>El \u00e9nfasis comenz\u00f3 con un art\u00edculo de 1998 del historiador Robert Brenner, \u00abLa econom\u00eda de la turbulencia global\u00bb&nbsp;<a href=\"https:\/\/newleftreview.org\/issues\/i229\">https:\/\/newleftreview.org\/issues\/i229<\/a>, un art\u00edculo que impresion\u00f3 e influy\u00f3 a muchos. Brenner se centr\u00f3 en el declive de la industria manufacturera en particular. Cuando Europa y Jap\u00f3n finalmente alcanzaron a Estados Unidos, la competencia capitalista se convirti\u00f3 en una especie de juego de suma cero que parec\u00eda producir mayoritariamente perdedores (aunque una serie de negativos no sume cero). Otros colaboradores de&nbsp;<em>NLR<\/em>&nbsp;han seguido escribiendo variaciones sobre este tema, entre ellos el soci\u00f3logo Aaron Benanav.<\/p>\n\n\n\n<p>En un reciente art\u00edculo para&nbsp;<em>Jacobin<\/em>&nbsp;(<a href=\"https:\/\/jacobin.com\/2023\/09\/robert-brenner-marxist-economics-falling-rate-of-profit-stagnation-overcapacity-industrial-policy\">https:\/\/jacobin.com\/2023\/09\/robert-brenner-marxist-economics-falling-rat\u2026<\/a>), Seth Ackerman disent\u00eda en\u00e9rgicamente de esta l\u00ednea de pensamiento; Benanav respondi\u00f3 poco despu\u00e9s (<a href=\"https:\/\/jacobin.com\/2023\/09\/robert-brenner-long-downturn-rate-of-profit-capitalism-stagnation-seth-ackerman-reply\">https:\/\/jacobin.com\/2023\/09\/robert-brenner-long-downturn-rate-of-profit-\u2026<\/a>). En lo que sigue, Benanav y Ackerman debaten la cuesti\u00f3n, conmigo como moderador. Puede encontrar una versi\u00f3n de audio de la discusi\u00f3n en mi programa,&nbsp;<em>Behind the News<\/em>&nbsp;(<a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/behind-the-news-how-sick-is-capitalism\/id791564318?i=1000629399725\">https:\/\/podcasts.apple.com\/us\/podcast\/behind-the-news-how-sick-is-capita\u2026<\/a>). (Suscr\u00edbase a&nbsp;<em>Jacobin Radio<\/em>&nbsp;para estar al d\u00eda:&nbsp;<a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/jacobin-radio\/id791564318\">https:\/\/podcasts.apple.com\/us\/podcast\/jacobin-radio\/id791564318<\/a>).<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Empecemos contigo, Aaron. Me ha llamado la atenci\u00f3n, leyendo tu material, que el punto de comparaci\u00f3n suele ser con el periodo 1950-73, los treinta o veintitr\u00e9s \u00aba\u00f1os gloriosos\u00bb, como dicen los franceses. Pero realmente fue una anomal\u00eda en la historia del capitalismo tras quince a\u00f1os de depresi\u00f3n y guerra. Las tasas de crecimiento de Estados Unidos no difieren mucho de las del \u00faltimo tercio del siglo XIX. Si nos fijamos en la relaci\u00f3n empleo-poblaci\u00f3n de Estados Unidos en la actualidad, ajustada al envejecimiento de la poblaci\u00f3n, est\u00e1 apenas un pelo por debajo de su m\u00e1ximo hist\u00f3rico, en abril de 2000. Los empresarios se quejan de la escasez de mano de obra.<\/p>\n\n\n\n<p>Yo no veo todo esto como una crisis. No estamos en una \u00e9poca dorada; vivimos en un mundo en declive. Tampoco parece una forma de enfermedad cr\u00f3nica. As\u00ed que, en realidad, \u00bfhasta qu\u00e9 punto est\u00e1 enfermo el capitalismo en t\u00e9rminos hist\u00f3ricos?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>Es una gran pregunta. Y es cierto que si comparamos la tasa de crecimiento de los \u00faltimos cuarenta a\u00f1os con la de 1870-1910, no es tan diferente en la mayor\u00eda de los pa\u00edses ricos. Creo que hay dos problemas con esa comparaci\u00f3n. Uno es que, como dije en mi libro sobre la automatizaci\u00f3n, creo que las tres \u00faltimas d\u00e9cadas del siglo XIX fueron un per\u00edodo de lucha de clases realmente intenso. Fue un per\u00edodo de grandes conflictos, el auge del socialismo, la pobreza end\u00e9mica y el desempleo. Y, ya sabes, fue una \u00e9poca muy turbulenta. Y creo que todos los esfuerzos de reforma que dieron lugar a la edad de oro, por excepcional que fuera, fueron reacciones a las dificultades que el capitalismo experiment\u00f3 en ese per\u00edodo.<\/p>\n\n\n\n<p>As\u00ed que creo que si quieres llamarlo capitalismo normal, estoy de acuerdo. Pero entonces deber\u00edas reconocer que el capitalismo normal para mucha gente es una crisis, y que en el pasado ese nivel de capitalismo normal ha generado una lucha social bastante intensa. Ahora, por supuesto, no hemos visto una lucha social intensa en los \u00faltimos cuarenta a\u00f1os. En realidad hemos visto lo contrario. Pero creo que las cosas han empezado a cambiar en los \u00faltimos diez a\u00f1os. Teor\u00edas como la de Robert Brenner, o la m\u00eda, son intentos de explicar por qu\u00e9 est\u00e1 ocurriendo eso.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Seth, en tu art\u00edculo argumentas que esta visi\u00f3n del estancamiento, el exceso de capacidad y la sensaci\u00f3n de crisis generalizada es esencial desde el punto de vista pol\u00edtico para marcar la diferencia entre reformistas y revolucionarios. \u00bfPodr\u00edas exponer ese argumento?<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>Bueno, es un argumento que se remonta a la \u00abcontroversia revisionista\u00bb dentro del marxismo en las d\u00e9cadas de 1890, 1900 y 1910. Aaron hace una buena observaci\u00f3n cuando dice que el capitalismo normal ha implicado a menudo un grado realmente intenso de lucha de clases y percepciones apocal\u00edpticas del desarrollo del capitalismo. Pero eso fue precisamente lo que ocurri\u00f3 con el estallido de la controversia revisionista en la d\u00e9cada de 1890, que comenz\u00f3 cuando Eduard Bernstein, que era una figura importante en los movimientos socialistas alem\u00e1n y europeo, un protegido de [Karl] Marx y [Friedrich] Engels, sali\u00f3 con una especie de replanteamiento, en el que abogaba por una v\u00eda reformista hacia el socialismo. Bas\u00f3 gran parte de esa argumentaci\u00f3n en las tendencias econ\u00f3micas, y concretamente en la idea de que las crisis eran cada vez menos apocal\u00edpticas, el sistema se estaba estabilizando y los altibajos eran cada vez menos catastr\u00f3ficos.<\/p>\n\n\n\n<p>Cuando se leen los textos de la controversia revisionista desde la perspectiva actual, se pueden esperar argumentos sobre la naturaleza del Estado o algo as\u00ed. Y hab\u00eda mucho de eso. Pero en realidad la mayor parte de la controversia se centraba en si el capitalismo se dirig\u00eda de nuevo hacia el tipo de turbulencia masiva que hab\u00eda experimentado en las d\u00e9cadas de 1870 y 1880. El argumento de Bernstein era que cuando se llega a las d\u00e9cadas de 1890 y 1900, se puede ver este tipo de estabilizaci\u00f3n que ocurre donde las tasas de crecimiento aumentaron un poco durante la era de la Belle Epoque anterior a la Primera Guerra Mundial. La premisa era que si el capitalismo alcanzaba un cierto grado de estabilidad \u2013 no ten\u00eda que ser necesariamente el nirvana \u2013 entonces eso alteraba fundamentalmente el argumento sobre la pol\u00edtica revolucionaria.<\/p>\n\n\n\n<p>Esa premisa fue b\u00e1sicamente aceptada por todas las partes. Y la discusi\u00f3n entonces era sobre los hechos. \u00bfSe ha estabilizado, de hecho, el capitalismo de la manera que Bernstein afirmaba? Robert Brenner est\u00e1 muy en la tradici\u00f3n de ese tipo de argumento dentro de la teor\u00eda marxista de la crisis. Ha argumentado con bastante claridad, junto con muchos de los que le siguen, que si se acepta su tesis del estancamiento global, eso tiene fuertes implicaciones para la pol\u00edtica socialista. No me queda claro c\u00f3mo separa exactamente Brenner el enfoque reformista del revolucionario en t\u00e9rminos pr\u00e1cticos, y supongo que es una pregunta dif\u00edcil de responder en general. Pero est\u00e1 claro que Brenner cree que su teor\u00eda fundamenta la posici\u00f3n revolucionaria.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Por supuesto, tuvimos una revoluci\u00f3n socialista en 1917. Gran Breta\u00f1a tuvo una depresi\u00f3n en los a\u00f1os veinte. Estados Unidos y el resto del mundo tuvieron una en 1930. As\u00ed que el capitalismo no era exactamente estable ni estaba de maravilla unas d\u00e9cadas despu\u00e9s de lo escrito por Bernstein.<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>Cuando se produjo la Primera Guerra Mundial y luego la Depresi\u00f3n, los marxistas m\u00e1s ortodoxos lo tomaron como una prueba de que Bernstein hab\u00eda hablado demasiado pronto. Pero, por supuesto, la noci\u00f3n de que esos acontecimientos catastr\u00f3ficos refutaban las afirmaciones de Bernstein depend\u00eda de la expectativa de que las tribulaciones del capitalismo llevar\u00edan al triunfo del socialismo. Y obviamente, a la larga, no fue as\u00ed.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Aaron, la idea de que, como dices en tu \u00faltimo art\u00edculo en&nbsp;<em>New Left Review<\/em>, \u00abel capitalismo se est\u00e1 agotando\u00bb, \u00bfes esencial para tu pol\u00edtica? \u00bfEs relevante para tu visi\u00f3n del mundo lo que se\u00f1ala Seth? Si el capitalismo no se est\u00e1 agotando, \u00bfen qu\u00e9 nos afecta?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>Bueno, aqu\u00ed me gustar\u00eda responder a algunos puntos m\u00e1s espec\u00edficos y basarme en la pregunta que ha planteado sobre las consecuencias de la controversia revisionista y el hecho de que fue seguida no por una estabilizaci\u00f3n del sistema, sino por dos guerras mundiales y la Depresi\u00f3n. Si nos fijamos en el trabajo de Robert Brenner y tratamos de situarlo con respecto a la tradici\u00f3n marxista, yo s\u00f3lo dir\u00eda que Seth se equivoca de genealog\u00eda aqu\u00ed de una manera realmente importante, porque en mi opini\u00f3n, Brenner forma parte de un grupo de marxistas de posguerra que eran quiz\u00e1s algo m\u00e1s como neoschumpeterianos. El punto era que ellos teorizaban esas ondas largas de las que estamos hablando.<\/p>\n\n\n\n<p>Teorizaban esta alternancia entre periodos de alto crecimiento capitalista -con capacidad para aceptar reformas y para que las organizaciones de la clase obrera obtengan conquistas mediante estrategias del tipo de colaboraci\u00f3n de clases- y periodos de lento crecimiento capitalista, que ocultan la competencia y el conflicto, y cambian el car\u00e1cter de la pol\u00edtica de la clase obrera y c\u00f3mo puede alcanzar el \u00e9xito. Y sin duda podemos hablar m\u00e1s de eso.<\/p>\n\n\n\n<p>S\u00f3lo quiero se\u00f1alar que entre los te\u00f3ricos de la onda larga, lo que distingue a Brenner es que descubri\u00f3 el estancamiento secular en el curso de su trabajo. Pero creo que es muy importante decir que lleg\u00f3 a ese punto de vista a trav\u00e9s de una confrontaci\u00f3n con la duraci\u00f3n y la persistencia de la recesi\u00f3n. Pero eso sale de esta tradici\u00f3n m\u00e1s amplia de la que forma parte, que yo considero como una especie de marxismo neoschumpeteriano. Tambi\u00e9n se puede pensar en ella como la teor\u00eda de la onda larga. Todas las teor\u00edas de onda larga, de las que forma parte la de Brenner, intentan situarnos con respecto a esos ciclos m\u00e1s largos.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>\u00bfHasta qu\u00e9 punto es esencial la crisis para su pol\u00edtica?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>El estancamiento es esencial. La idea de vivir en la depresi\u00f3n de una ola tiene implicaciones para la pol\u00edtica; es algo que podemos reconocer a nuestro alrededor ahora mismo. F\u00edjese en lo que est\u00e1 ocurriendo con la United Auto Workers (UAW), \u00bfverdad? Hemos vivido cuarenta a\u00f1os de derrota obrera a largo plazo. Esa derrota no ha sido s\u00f3lo a manos de una embestida de los capitalistas, aunque creo que es bien sabido. Y una gran parte de eso es la observaci\u00f3n, de la que no creo que Seth hable en absoluto en su art\u00edculo, de que una gran caracter\u00edstica de los \u00faltimos cuarenta a\u00f1os ha sido un importante aumento de la participaci\u00f3n del capital en la renta y la disminuci\u00f3n de la participaci\u00f3n del trabajo en la renta, y que los sindicatos de la clase obrera y los partidos socialdem\u00f3cratas de todo el mundo han organizado esa derrota. No han luchado contra ella, la han organizado y han participado en ella. Eso tiene mucho que ver con la p\u00e9rdida de legitimidad de esos \u00f3rganos.<\/p>\n\n\n\n<p>Tambi\u00e9n explica por qu\u00e9 en el per\u00edodo contempor\u00e1neo, estamos viendo no s\u00f3lo una curva ascendente de descontento social, sino tambi\u00e9n esfuerzos por parte de grupos pol\u00edticos y grupos de trabajadores para liberarse de esos \u00f3rganos preexistentes y tratar de encontrar nuevas formas de organizaci\u00f3n que sean m\u00e1s combativas. Creo que es dif\u00edcil entender tanto la lucha por el sindicalismo democr\u00e1tico en la UAW -y su \u00e9xito como el hecho de que diera lugar inmediatamente a una postura mucho m\u00e1s combativa por parte de los trabajadores del autom\u00f3vil- sin situarla dentro de esta perspectiva de la ola larga.<\/p>\n\n\n\n<p>No soy un te\u00f3rico de la onda larga. Tengo una idea de por qu\u00e9 esta onda es m\u00e1s una onda de tipo estancamiento secular de lo que los te\u00f3ricos de la onda larga imaginaron que ser\u00eda. Pero creo que estas perspectivas son bastante esenciales para entender no s\u00f3lo mi pol\u00edtica, sino la pol\u00edtica del momento.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Seth, \u00bfuna respuesta?<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>En primer lugar, estoy de acuerdo -y creo que es cierto que no es un aspecto del que haya hablado mucho en mi art\u00edculo- en que existe este aspecto schumpeteriano de onda larga en la obra de Brenner, y que est\u00e1 relacionado con su pol\u00edtica. Y esta es una idea que se oye mucho -no s\u00f3lo en la izquierda, en realidad, sino a menudo desde una perspectiva dominante- que los per\u00edodos de fuerte crecimiento, una econom\u00eda en auge, las condiciones de tipo \u00abedad de oro\u00bb son propicias para, o al menos m\u00e1s permisivas para, la reforma, la socialdemocracia, los tipos igualitarios de pol\u00edtica; y en los per\u00edodos de menor crecimiento o m\u00e1s turbulencia econ\u00f3mica ese es menos el caso.<\/p>\n\n\n\n<p>No quiero poner palabras en la boca de Brenner en este punto, pero creo que cualquiera que haya estado en la izquierda, especialmente desde 2008, sabe que en el discurso ambiental de la izquierda, hay un patr\u00f3n familiar de argumento que b\u00e1sicamente detiene cualquier discusi\u00f3n de cualquier tipo de reformas que quieras discutir con la idea de que vivimos en una \u00e9poca de estancamiento o de crisis o como quieras llamarlo, y eso descarta las reformas. El sistema no puede dar esas reformas que quieres, ese tipo de argumento. Lo cual, en mi opini\u00f3n, no describe realmente la naturaleza del problema al que nos enfrentamos.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Nunca he entendido ese argumento, porque \u00bfno se puede obligar al sistema a hacerlo? Eso es lo que el Estado puede hacer, al menos en teor\u00eda.<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>La conceptualizaci\u00f3n del capitalismo desde ese punto de vista es aquella en la que todo lo que ocurre es a placer o, en \u00faltima instancia, por decisi\u00f3n del capital. Y el capital se muestra m\u00e1s abierto cuando las tasas de crecimiento son altas y cuando los beneficios son elevados. Por lo tanto, cualquier reforma que hayamos conseguido es porque en \u00faltima instancia era aceptable para el capital, pero ahora no lo es. Creo que eso es una interpretaci\u00f3n err\u00f3nea de c\u00f3mo conseguimos las reformas que conseguimos.<\/p>\n\n\n\n<p>Se habla mucho de crecimiento sin hacer una distinci\u00f3n importante. El crecimiento del PIB puede dividirse en dos partes: el crecimiento del empleo, por un lado, y el crecimiento de la productividad, es decir, la producci\u00f3n por trabajador, por otro. Y es una distinci\u00f3n realmente importante porque si el crecimiento, digamos, se ralentiza, y la ralentizaci\u00f3n se debe a una ralentizaci\u00f3n del crecimiento del empleo y el resultado es que hay mucha gente que necesita trabajo, que quiere trabajo, pero no puede encontrarlo, entonces eso, en primer lugar, es puro despilfarro. Y eso indica un claro fracaso del sistema y un fracaso de la pol\u00edtica p\u00fablica. No hay justificaci\u00f3n para un sistema que permite a mucha gente estar ociosa cuando no quieren estarlo, cuando podr\u00edan estar contribuyendo a la sociedad.<\/p>\n\n\n\n<p>Y adem\u00e1s de eso, tiene efectos tremendos en el tono de la pol\u00edtica, y de la pol\u00edtica de clases en particular. Obviamente, en periodos de desempleo masivo, la clase trabajadora est\u00e1 a la defensiva, mientras que tiene una posici\u00f3n mucho m\u00e1s fuerte en periodos de auge. Y en ese sentido, esto sugiere una especie de conclusi\u00f3n opuesta a la idea de que los per\u00edodos de fuerte crecimiento y altos beneficios son per\u00edodos en los que la clase dominante est\u00e1 m\u00e1s dispuesta a ceder. En realidad es m\u00e1s bien lo contrario: los periodos de fuerte crecimiento son periodos en los que la naturaleza competitiva del sistema significa que los capitalistas son mucho m\u00e1s dependientes de la clase trabajadora en el sentido de estar siempre escasos de trabajadores, escasos de mano de obra, y eso da a los trabajadores una mayor capacidad para extraer concesiones que los capitalistas no estar\u00edan dispuestos a otorgar de otro modo.<\/p>\n\n\n\n<p>Pero si la ralentizaci\u00f3n del crecimiento no tiene que ver con una ralentizaci\u00f3n del empleo, si no tiene que ver con el aumento del desempleo, el desempleo masivo, la gente ociosa, la debilidad de los mercados laborales, si se trata en cambio de una ralentizaci\u00f3n de la tasa de crecimiento de la productividad, y especialmente del crecimiento de la productividad en los pa\u00edses m\u00e1s ricos, los pa\u00edses donde el nivel de productividad es ya el m\u00e1s alto del mundo, creo que el significado de eso, pol\u00edtica y econ\u00f3micamente, es completamente diferente y un poco ambiguo.<\/p>\n\n\n\n<p>Ahora mismo, como ha se\u00f1alado Doug, el nivel de empleo en Estados Unidos es muy, muy alto. La tasa de empleo es m\u00e1s alta que nunca. En la medida en que hay una desaceleraci\u00f3n del crecimiento, es porque el trabajador medio est\u00e1 produciendo una cantidad de producto que est\u00e1 creciendo a un ritmo m\u00e1s lento de lo que lo hizo, digamos, en la posguerra, pero a partir de un nivel que es mucho, mucho m\u00e1s alto.<\/p>\n\n\n\n<p>As\u00ed, en el pico de la edad de oro, a principios de 1960, el nivel de renta per c\u00e1pita en los Estados Unidos era como un tercio de lo que es ahora en t\u00e9rminos reales. Ahora, tomemos las previsiones de Robert J. Gordon, una fuente que Aaron ha mencionado un mont\u00f3n de veces en sus escritos, un macroeconomista muy convencional con una especie de interpretaci\u00f3n sombr\u00eda del crecimiento econ\u00f3mico y sus perspectivas, dadas las realidades tecnol\u00f3gicas y el perfil de la productividad. Hace poco public\u00f3 un art\u00edculo en el que pronosticaba la trayectoria m\u00e1s probable del crecimiento de la productividad laboral en Estados Unidos a largo plazo. Y presentaba esta previsi\u00f3n como una visi\u00f3n muy pesimista. Era, creo, del 1,2% anual. Un 1,2% anual significa que el nivel de productividad y de renta per c\u00e1pita se duplicar\u00e1 en unos sesenta a\u00f1os, partiendo de un nivel que ya es tres veces superior al del punto \u00e1lgido de la posguerra.<\/p>\n\n\n\n<p>Una cosa es hablar de productividad en los pa\u00edses pobres, donde hay que ponerse al d\u00eda. Pero la idea de que la econom\u00eda se duplique en sesenta a\u00f1os, en lugar de, digamos, triplicarse, en los pa\u00edses donde ya est\u00e1 en su nivel m\u00e1s alto\u2026 a m\u00ed me parece uno de los aspectos menos importantes de d\u00f3nde est\u00e1 fallando el capitalismo.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>S\u00ed, todos deber\u00edamos tener esos problemas. Aaron, \u00bfuna respuesta a eso?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>Me alegro mucho de que Seth haya sacado el tema, porque creo que llega al quid de la cuesti\u00f3n. Y s\u00f3lo para exponer mi punto de vista de forma concisa, creo que la cuesti\u00f3n es que el descenso de la tasa de beneficios que Brenner identific\u00f3 en los a\u00f1os setenta y ochenta, todo su an\u00e1lisis de la tasa de beneficios, consist\u00eda en decir que las razones de este descenso de la rentabilidad proven\u00edan de un descenso de la productividad del capital: una disminuci\u00f3n de las adiciones que se pueden obtener a los ingresos por cada unidad adicional de capital que se aporta, no un aumento de la participaci\u00f3n de los salarios en los ingresos o de la participaci\u00f3n de la mano de obra en los ingresos. No fue el \u00e9xito de la lucha de los trabajadores. Pero esta otra cosa, la ca\u00edda de la productividad del capital, era un problema.<\/p>\n\n\n\n<p>Y Brenner argument\u00f3 sobre los a\u00f1os 70 que pensaba que esto se deb\u00eda a un exceso de capacidad. Una vez que hizo ese argumento, dijo que porque \u00e9l pensaba que pa\u00edses como Alemania y Jap\u00f3n ten\u00edan mucho m\u00e1s por recorrer, no hab\u00edan alcanzado a los Estados Unidos en t\u00e9rminos de productividad. Por eso dijo que no pod\u00eda atribuirlo a una especie de agotamiento o llegada de la frontera tecnol\u00f3gica.<\/p>\n\n\n\n<p>Mi opini\u00f3n es que hizo demasiado hincapi\u00e9 en ese argumento porque con el tiempo, y en esto tambi\u00e9n estoy de acuerdo con Robert J. Gordon, aunque m\u00e1s con Dietrich Vollrath, se trata menos de innovaciones de productos e innovaciones de procesos, se trata m\u00e1s de desindustrializaci\u00f3n y del auge del sector servicios que de un agotamiento tecnol\u00f3gico general.<\/p>\n\n\n\n<p>Pero la cuesti\u00f3n es que, a largo plazo, la raz\u00f3n de ese descenso de la productividad del capital tiene m\u00e1s que ver con el descenso de la productividad del trabajo, y eso es algo que podemos observar directamente. No necesitamos intentar argumentar bas\u00e1ndonos en las tasas de beneficio. Y tambi\u00e9n creo que es por eso que la mayor\u00eda de los partidarios del estancamiento secular como Gordon o Vollrath no hacen su argumento por referencia a las tasas de beneficio, sino que est\u00e1n hablando de una desaparici\u00f3n de las oportunidades de inversi\u00f3n en ese sentido. Es algo que podemos observar directamente de esta manera.<\/p>\n\n\n\n<p>Ahora bien, \u00bfpor qu\u00e9 es eso un problema? Si estuvi\u00e9ramos hablando de un sistema que oscila entre un crecimiento del 3% y un crecimiento del 1% y que, con el tiempo, alcanza una media del 2%, no veo por qu\u00e9 habr\u00eda motivos para quejarse. Creo que no es un argumento irrazonable. Pero no creo que refleje la realidad. Y creo que ah\u00ed es donde este tema del aumento de la cuota de capital se vuelve realmente importante. Y creo que es algo a lo que Seth no presta suficiente atenci\u00f3n, porque el punto aqu\u00ed es que los capitalistas respondieron a una disminuci\u00f3n de sus propios ingresos en la d\u00e9cada de 1970, con la ca\u00edda de las tasas de ganancia, comenzando a hacer esta batalla realmente intensa sobre los niveles de vida de la clase trabajadora.<\/p>\n\n\n\n<p>Y obviamente tuvieron m\u00e1s \u00e9xito en algunos lugares que en otros. Pero el efecto ha sido transformar radicalmente nuestras instituciones, el estado del bienestar, el car\u00e1cter de la inseguridad de los trabajadores. Quiero decir, ciertamente vivimos en un periodo de alto empleo ahora mismo, pero no soy el \u00fanico que piensa que puede ser una condici\u00f3n temporal. Y desde luego no es la trayectoria de los \u00faltimos cuarenta a\u00f1os. Ser\u00eda un an\u00e1lisis muy extra\u00f1o del periodo desde los a\u00f1os 70 decir simplemente, bueno, todo continu\u00f3 m\u00e1s o menos como estaba. S\u00f3lo que la tasa de crecimiento de los ingresos se ralentiz\u00f3. As\u00ed que creo que la cuesti\u00f3n a la que nos enfrentamos ahora es si podemos, a trav\u00e9s del est\u00edmulo, aumentar la tasa de crecimiento de la productividad, porque muchas de estas soluciones keynesianas m\u00e1s radicales dependen de que la acumulaci\u00f3n de deuda tenga el efecto de aumentar la tasa de crecimiento. Y creo que esas cosas est\u00e1n en entredicho.<\/p>\n\n\n\n<p>En estos momentos, uno de los grandes debates en torno a estas cuestiones es que, durante los \u00faltimos cuarenta a\u00f1os, los esfuerzos por estimular la econom\u00eda han generado cada vez menos inversi\u00f3n y se han limitado a llenar los bolsillos de las \u00e9lites mediante la recompra de acciones y otras estrategias que privilegian el aumento de la riqueza de las \u00e9lites, de su riqueza personal y de su gasto personal, por encima de la inversi\u00f3n en la construcci\u00f3n de las infraestructuras que la sociedad construy\u00f3.<\/p>\n\n\n\n<p>Si s\u00f3lo vamos a crecer al 1%, una sociedad racional podr\u00eda decir: utilicemos esto para asegurarnos de que tenemos suficientes hospitales en caso de que haya una pandemia. Eso no es lo que ocurre. Y creo que llega a este punto exacto, que es que las luchas en estas condiciones de bajo crecimiento de la productividad en una sociedad basada en clases son realmente intensas luchas sobre lo que sucede con ese peque\u00f1o excedente. Y hasta ahora ha sido muy dif\u00edcil, incluso para la administraci\u00f3n Biden, para cualquiera, imaginar realmente una lucha lo suficientemente dura como para cambiar los t\u00e9rminos del car\u00e1cter de clase de la sociedad, alej\u00e1ndose de los ingresos y el consumo de las \u00e9lites y acerc\u00e1ndose realmente a la inversi\u00f3n en las cosas que necesitamos para mejorar nuestras vidas.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Hablemos un poco de, como se dice en&nbsp;<em>New Left Review<\/em>, la coyuntura actual. Hemos asistido a una inflaci\u00f3n reciente, una inflaci\u00f3n bastante sorprendente para la mayor\u00eda de la gente. Ahora est\u00e1 remitiendo, pero no ha desaparecido. Fue causada por lo contrario del exceso de capacidad. Mostr\u00f3 un sistema productivo que estaba realmente al l\u00edmite con inventarios justo a tiempo subcontratados en medio mundo. A esto hay que a\u00f1adir los cheques \u00abest\u00edmulo\u00bb y el ocio forzado, lo que significaba que la gente no gastaba dinero en restaurantes, sino en bienes duraderos. Vimos aumentar las tasas de beneficios, lo que contradec\u00eda las historias de ca\u00edda de las tasas de beneficios. As\u00ed que no se parec\u00eda en nada a esta imagen de estancamiento cr\u00f3nico.<\/p>\n\n\n\n<p>\u00bfSe trataba de una extra\u00f1a -por citar un verso de Wallace Stevens- \u00abllamarada de paja de verano en la mella del invierno\u00bb?&nbsp; \u00bfFue s\u00f3lo un momento extra\u00f1o que va a desaparecer? \u00bfO nos dice algo sobre cuestiones m\u00e1s estructurales?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>No puedo predecir el futuro \u2013 quiero decir, en el momento actual se habla mucho de qu\u00e9 tipo de est\u00edmulo puede soportar la econom\u00eda y hacia d\u00f3nde debe dirigirse. Pero s\u00ed creo que las dislocaciones de la era COVID se debieron a la era COVID. No creo que nadie crea que la ruptura de las cadenas de suministro y la incapacidad de la gente para importar todas estas cosas que se est\u00e1n produciendo en el extranjero fueran el signo de una transformaci\u00f3n a largo plazo de las capacidades del sistema. Fue un momento de crisis, y exigi\u00f3 medidas intensas y combativas. Creo que una caracter\u00edstica realmente triste del presente es, obviamente, que la mayor\u00eda de las medidas de bienestar que se aplicaron en aquel momento han retrocedido. No creo que hayamos hecho ning\u00fan tipo de avance permanente a trav\u00e9s de este aumento temporal de la generosidad del Estado del bienestar.<\/p>\n\n\n\n<p>Creo que hay algo de raz\u00f3n en la preocupaci\u00f3n de que esto podr\u00eda terminar siendo una situaci\u00f3n temporal y que la tasa de crecimiento de la productividad a largo plazo de la econom\u00eda probablemente no est\u00e1 cambiando debido a las inversiones en la industria manufacturera \u2013 que son grandes para los conflictos militares de Estados Unidos y m\u00e1s a\u00fan sobre las guerras comerciales y cualquier otro tipo de guerras con China. La industria manufacturera ya no es una parte tan importante de la econom\u00eda, e incluso un est\u00edmulo importante a ese sector no va a tener un gran efecto en nuestras tasas de crecimiento de la productividad o la econom\u00eda en su conjunto.<\/p>\n\n\n\n<p>As\u00ed que creo que la idea de que el estancamiento podr\u00eda volver est\u00e1 justificada como tesis. Creo que el hecho de que sea una opini\u00f3n tan generalizada y que est\u00e9 influyendo en muchos responsables pol\u00edticos y en los esfuerzos por pensar en c\u00f3mo podr\u00eda ser el futuro es tambi\u00e9n algo que ignoramos por nuestra cuenta y riesgo. Tratar de atribuir este punto de vista a Robert Brenner es como entrar en una casa en llamas y tratar de encontrar la vela y apagarla. Se trata de opiniones muy extendidas sobre las limitaciones del futuro. Y no estoy diciendo que en la izquierda debamos sentirnos limitados por ellas, creo que esa es una historia m\u00e1s larga y compleja. Pero son cuestiones serias sobre las que reflexionar.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Seth, \u00bfalg\u00fan comentario al respecto?<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>Bueno, creo que hay un deslizamiento real en el argumento de Aaron cuando pasa de se\u00f1alar las preocupaciones de personas como Larry Summers o Robert J. Gordon u Olivier Blanchard sobre las tasas de crecimiento, y el renacimiento de la teor\u00eda del estancamiento secular \u2013 y siempre he pensado que Larry Summers era muy sensato al respecto, que ten\u00eda raz\u00f3n \u2013 y luego se\u00f1alar eso como una indicaci\u00f3n de que lo que Robert Brenner est\u00e1 diciendo no puede ser tan loco, porque mira a todas estas personas muy sensatas haciendo el mismo argumento. No es en absoluto el mismo argumento.<\/p>\n\n\n\n<p>Todo el sentido de la reintroducci\u00f3n de Larry Summers de la teor\u00eda del estancamiento secular era decir que ha habido un est\u00edmulo fiscal inadecuado. Tanto si se est\u00e1 de acuerdo con \u00e9l como si no, su argumento es que ha habido un est\u00edmulo fiscal inadecuado durante los \u00faltimos treinta o cuarenta a\u00f1os porque las tendencias de crecimiento de la poblaci\u00f3n y otros factores estructurales a largo plazo han reducido la demanda natural de inversi\u00f3n, de inversi\u00f3n privada, y esto ha hecho que la carga del ajuste recayera por completo en la pol\u00edtica monetaria, de modo que forz\u00f3 a los tipos de inter\u00e9s a bajar cada vez m\u00e1s hasta que finalmente llegaron a cero. Ese es el argumento. Y su conclusi\u00f3n es que el gobierno necesita gastar mucho m\u00e1s dinero, y cuando gasta mucho m\u00e1s dinero, probablemente deber\u00eda centrarse en la inversi\u00f3n \u2013 cosas que realmente aumenten la capacidad productiva de la econom\u00eda \u2013 y si hacemos eso, funcionar\u00e1. Se puede hacer lo que se quiera con ese argumento, pero es 180 grados opuesto a lo que Brenner siempre ha estado machacando, que es la idea de que el llamado estancamiento que hemos estado experimentando es algo que no se puede abordar con el gobierno gastando m\u00e1s dinero. Son dos argumentos distintos que es importante mantener separados.<\/p>\n\n\n\n<p>Sobre la inflaci\u00f3n que hemos visto en los \u00faltimos a\u00f1os, mi opini\u00f3n es que casi con toda seguridad fue temporal y que est\u00e1 desapareciendo y desaparecer\u00e1. Hay argumentos de personas sensatas como Charles Goodhart, que ha apuntado a las tendencias demogr\u00e1ficas a largo plazo y ha argumentado que las fuerzas que provocaron el estancamiento secular en las \u00faltimas d\u00e9cadas se est\u00e1n invirtiendo lentamente y que con el tiempo empezaremos a ver un repunte en la tasa natural de demanda de inversi\u00f3n. Y eso va a conducir a presiones de la demanda, y vas a empezar a ver la inflaci\u00f3n como un problema de nuevo. Ya sabes, tal vez eso es cierto. Realmente no lo s\u00e9. No lo he investigado.<\/p>\n\n\n\n<p>Pero todo esto es un recordatorio importante de que una gran parte de la historia \u2013 y para m\u00ed, la parte central de la historia de lo que sucedi\u00f3 desde la d\u00e9cada de 1970 \u2013 fue sobre el dinero, los salarios y la inflaci\u00f3n. El movimiento obrero de la posguerra se hizo muy fuerte. Hab\u00eda pleno empleo. Y hay una incompatibilidad natural \u2013 no necesariamente una incompatibilidad absoluta, pero es dif\u00edcil conciliar el pleno empleo y el dinero estable. Y la crisis que se produjo en los a\u00f1os 70 en torno al valor del dinero y la inflaci\u00f3n acab\u00f3 provocando toda una serie de enormes reorganizaciones institucionales, m\u00e1s claramente observables en Europa, pero de diferentes maneras en todo el mundo. Eso tuvo un enorme efecto en todos los temas de los que estamos hablando, incluyendo especialmente el tema del desempoderamiento de la clase trabajadora en las \u00faltimas d\u00e9cadas.<\/p>\n\n\n\n<p>Porque se convirti\u00f3 en una cuesti\u00f3n de pol\u00edtica p\u00fablica d\u00eda tras d\u00eda en los bancos centrales para asegurarse de que la tasa de crecimiento del empleo no fuera demasiado baja, pero tampoco demasiado alta. En los \u00faltimos a\u00f1os esto se ha vuelto menos importante debido al estancamiento secular, el l\u00edmite inferior cero de los tipos de inter\u00e9s que les hizo preocuparse cada vez m\u00e1s por el crecimiento del empleo demasiado lento. Pero, durante la mayor parte de las \u00faltimas d\u00e9cadas, hemos tenido un objetivo pol\u00edtico deliberado por parte de las instituciones pol\u00edticas m\u00e1s poderosas de los gobiernos de los pa\u00edses ricos, los bancos centrales, para lograr tasas de desempleo que fueran ciertamente m\u00e1s altas de lo que se podr\u00eda conseguir de otro modo. Y creo que si no se tiene en cuenta este aspecto, no se puede entender c\u00f3mo hemos llegado a una situaci\u00f3n en la que la clase trabajadora est\u00e1 tan desprotegida y las tasas de crecimiento son inusualmente bajas.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Aaron, Seth plante\u00f3 la cuesti\u00f3n en su art\u00edculo, que tambi\u00e9n se me ocurri\u00f3 mientras le\u00eda tu material: \u00bfC\u00f3mo puede haber un exceso de capacidad cr\u00f3nico y una falta de inversi\u00f3n cr\u00f3nica al mismo tiempo? \u00bfNo se pudrir\u00eda el exceso de capacidad con el tiempo?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>Esta es una buena oportunidad para responder a otra cosa que ha dicho Seth sobre el estancamiento secular. Mi explicaci\u00f3n de esto es simplemente que tiene sentido una vez que te das cuenta de que estamos hablando de desindustrializaci\u00f3n. No estamos hablando de c\u00f3mo era la industria en el siglo XIX o incluso en la d\u00e9cada de 1950. No estamos hablando de un periodo de industrializaci\u00f3n o de un aumento de la participaci\u00f3n de la industria en el PIB. Estamos hablando de un sector de la econom\u00eda que est\u00e1 viendo caer su participaci\u00f3n en el PIB, y que limita la medida en que las cuestiones de crecimiento de los ingresos y un aumento del tama\u00f1o del mercado en la industria y en todos estos diferentes campos ha dado lugar a una situaci\u00f3n de salida lenta y persistente. Eso, para m\u00ed, no es tan diferente de lo que sucedi\u00f3 en la agricultura, si se hace realmente a vista de p\u00e1jaro.<\/p>\n\n\n\n<p>Por supuesto, en realidad es mucho m\u00e1s complicado, en parte porque el destino de la industria tiene unas implicaciones geopol\u00edticas tan enormes que los gobiernos intervinieron de todo tipo de formas para intentar modificar y transformar la v\u00eda de la desindustrializaci\u00f3n y tambi\u00e9n para presionar sobre las consecuencias que ten\u00eda en otros pa\u00edses moviendo los valores monetarios de un lado a otro o mediante otras formas de inversi\u00f3n o protecci\u00f3n estatal. Si se piensa como Brenner, que se trata de una historia sobre la econom\u00eda en su conjunto, entonces es dif\u00edcil explicarla en t\u00e9rminos de exceso de capacidad. Pero si se piensa en ello en el contexto de la desindustrializaci\u00f3n, como la desagrarizaci\u00f3n, entonces es bastante f\u00e1cil entender c\u00f3mo puede suceder.<\/p>\n\n\n\n<p>Y por eso, de nuevo, lo que dije es que mi opini\u00f3n es que la historia de Brenner sobre el exceso de capacidad se aplica en los a\u00f1os 70 y 80, pero cada vez m\u00e1s con el tiempo, la raz\u00f3n de la baja productividad del capital es s\u00f3lo la baja productividad del trabajo. Y ah\u00ed es donde la historia converge en mi relato, m\u00e1s con William Baumol y Vollrath que con Gordon. Pero es la misma idea b\u00e1sica que desde los a\u00f1os 70, el potencial de crecimiento de la econom\u00eda, dado por las tasas de crecimiento de la productividad, ha disminuido, y el per\u00edodo del gran aumento de las tasas de participaci\u00f3n de las mujeres en la poblaci\u00f3n activa y los efectos continuados del \u00abbaby boom\u00bb ocultaron en cierta medida esto aumentando el total de horas, o la tasa de crecimiento de las horas. As\u00ed, aunque la productividad no creciera tan r\u00e1pidamente, las horas de trabajo s\u00ed lo hac\u00edan.<\/p>\n\n\n\n<p>Pero ahora estamos al final de esa fase, y la transici\u00f3n a los servicios se ha hecho mucho m\u00e1s extrema con el tiempo. Pa\u00edses como Alemania y Jap\u00f3n han logrado tasas de crecimiento de la productividad en el conjunto de la econom\u00eda del orden de menos del 1% anual durante los \u00faltimos veinte a\u00f1os. Y estos son pa\u00edses que ahora est\u00e1n en declive demogr\u00e1fico. Estas son las razones por las que creo que existe un problema a largo plazo. Y no s\u00e9 lo que Larry Summers piensa hoy, pero no creo que la explicaci\u00f3n de que esto es s\u00f3lo de un problema de ahorro demasiado alto y no un problema de falta de oportunidades de inversi\u00f3n tenga sentido. Es decir, la idea misma de que necesitamos inversi\u00f3n p\u00fablica sugiere que hay alg\u00fan problema a la hora de traducir el ahorro en inversi\u00f3n que deber\u00eda ser examinado m\u00e1s de cerca y creo que lleva directamente a estas explicaciones tipo Gordon\/Vollrath de por qu\u00e9 es as\u00ed.<\/p>\n\n\n\n<p>Creo que esto marca la pauta para pensar en el futuro. Y, obviamente, decir eso no significa que debamos resignarnos a una situaci\u00f3n de estancamiento de los ingresos de la clase trabajadora y de rapacidad de las \u00e9lites y no hacer una transici\u00f3n adecuada hacia el Nuevo Pacto Verde. Y tambi\u00e9n es por eso que en mi trabajo he prestado mucha atenci\u00f3n a la radicalizaci\u00f3n de los keynesianos y a la afirmaci\u00f3n de repente, despu\u00e9s de setenta a\u00f1os, de que la soluci\u00f3n a estos problemas no es estimular el consumo -que durante los \u00faltimos setenta a\u00f1os se ha convertido sobre todo en crecimiento de la renta de las \u00e9lites en lugar de m\u00e1s inversi\u00f3n- sino a trav\u00e9s de una campa\u00f1a coordinada de inversi\u00f3n p\u00fablica.<\/p>\n\n\n\n<p>Y por eso en el libro que estoy escribiendo ahora hablo de los peligros de la tecnocracia y de por qu\u00e9 deber\u00edamos apoyar una transici\u00f3n hacia una econom\u00eda p\u00fablica al tiempo que nos mostramos esc\u00e9pticos sobre las capacidades de los keynesianos para realmente hacer girar esa econom\u00eda en una direcci\u00f3n humana. Las preocupaciones sobre el ruido de sables tampoco son irrelevantes en este caso.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>[John Maynard] Keynes ten\u00eda esa parte al final de la&nbsp;<em>Teor\u00eda General<\/em>&nbsp;cuando hablaba de la socializaci\u00f3n de la inversi\u00f3n. Era muy vago en lo que quer\u00eda decir con eso, pero parec\u00eda que significaba que la \u00e9lite como \u00e9l deb\u00eda hacerse cargo de la inversi\u00f3n y quit\u00e1rsela a los capitalistas. Pero ese control de la inversi\u00f3n se perdi\u00f3 a partir de la atenci\u00f3n que se prest\u00f3 a la regulaci\u00f3n del ciclo econ\u00f3mico y al fomento del consumo.<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>S\u00ed, y esa fue una respuesta muy razonable, creo, a lo que ocurri\u00f3 durante el gran boom. Creo que no se puede hablar de eso sin hablar de la derrota de la actividad de la clase obrera inmediatamente despu\u00e9s de la Segunda Guerra Mundial y de la especie de alejamiento de cualquier relevancia de los keynesianos m\u00e1s radicales, que tambi\u00e9n ocurri\u00f3 muy r\u00e1pidamente.<\/p>\n\n\n\n<p>El punto de todo esto es que esa versi\u00f3n del keynesianismo hizo que el keynesianismo estuviera realmente mal equipado para manejar las crisis de los a\u00f1os 70, y las batallas por una econom\u00eda p\u00fablica m\u00e1s radical se perdieron en ese momento. Y as\u00ed es como hemos llegado a donde estamos hoy. Quiero decir, es una historia de clase, \u00bfno? Al final, la historia que contaba Seth sobre las mayores tasas de desempleo desde los a\u00f1os 70 y los movimientos de los bancos centrales, es una historia sobre el conflicto de clases, \u00bfno?<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Seth, en tu art\u00edculo argumentas que debido a que medimos mal la depreciaci\u00f3n \u2013 concretamente, las autoridades estadounidenses miden mal la depreciaci\u00f3n \u2013 el stock de capital es en realidad menor de lo que es, lo que hace que la tasa de beneficios sea mayor. As\u00ed que todas estas historias de una tasa de beneficios decreciente son producto de estad\u00edsticas enga\u00f1osas. Pero si eso es cierto, si la tasa de beneficios es realmente m\u00e1s alta de lo que creemos, \u00bfpor qu\u00e9 las tasas de inversi\u00f3n no son m\u00e1s altas de lo que son?<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>Creo que hay una respuesta bastante directa a esta pregunta. Hace poco, un par de economistas de la Universidad de Chicago publicaron un magn\u00edfico art\u00edculo sobre el que probablemente escribir\u00e9 algo pronto.&nbsp;<em>\u00abCorporate Discount Rates\u00bb<\/em>&nbsp;era el aburrido t\u00edtulo del art\u00edculo, pero trataba de un tema muy querido para ti, Doug, pensando en tu libro&nbsp;<em>Wall Street<\/em>. Aqu\u00ed, creo que hay una disyuntiva real con la opini\u00f3n que dice que en la medida en que ha habido una desaceleraci\u00f3n del crecimiento, es porque las empresas ven menos oportunidades de inversi\u00f3n.<\/p>\n\n\n\n<p>Lo que hicieron estos economistas fue revisar miles de transcripciones de llamadas de resultados en las que los ejecutivos explican a los inversores, accionistas y gestores de activos lo que est\u00e1n haciendo y lo que est\u00e1n pensando. Y muy a menudo en estas llamadas, los CEOs explican lo que actualmente utilizan como su tasa cr\u00edtica de inversi\u00f3n, que por alguna raz\u00f3n los economistas que escribieron este documento llaman la \u00abtasa de descuento\u00bb: qu\u00e9 tasa de rendimiento requieren, cuando est\u00e1n considerando qu\u00e9 proyectos de inversi\u00f3n emprender o no emprender, para convencerlos de seguir adelante con el proyecto.<\/p>\n\n\n\n<p>Estos economistas no fueron los primeros en darse cuenta de que las tasas de descuento de una inversi\u00f3n empresarial han experimentado esta trayectoria tan peculiar. Porque supuestamente, seg\u00fan los libros de texto de econom\u00eda, una empresa deber\u00eda invertir en cualquier tipo de proyecto que ofrezca prospectivamente una tasa de rentabilidad superior a la que la empresa o sus accionistas podr\u00edan obtener en otra parte. Hay diferentes maneras de estimar cu\u00e1l es la tasa de rendimiento alternativa, ya sea la tasa media de rendimiento del S&amp;P 500, o podr\u00eda ser el tipo de inter\u00e9s sin riesgo m\u00e1s la adici\u00f3n de alg\u00fan factor de riesgo o lo que sea.<\/p>\n\n\n\n<p>Pero la cuesti\u00f3n es que a medida que el capital se abarata, lo que ha ocurrido en t\u00e9rminos financieros en los \u00faltimos treinta o cuarenta a\u00f1os, exactamente por estas razones de estancamiento secular, los tipos de inter\u00e9s han ca\u00eddo masivamente y los tipos de inter\u00e9s reales tambi\u00e9n han ca\u00eddo, no s\u00f3lo los nominales. Por lo tanto, deber\u00edamos ver una disminuci\u00f3n en la tasa de inter\u00e9s que las empresas utilizan. Deber\u00edan decir, bueno, si la tasa media de rentabilidad de la econom\u00eda es del 5% o el 6% en lugar del 9% o el 10%, eso significa que deber\u00edamos estar dispuestos a invertir en proyectos que tengan unas tasas de rentabilidad previstas un poco m\u00e1s bajas.<\/p>\n\n\n\n<p>Pero eso no ha ocurrido. Se han realizado encuestas entre directores financieros (la Universidad de Duke lleva muchos a\u00f1os realizando este tipo de encuestas) en las que se les pregunta cu\u00e1l es su tasa cr\u00edtica de rentabilidad. Y la tasa cr\u00edtica de rentabilidad no se ha movido en absoluto. Ha sido completamente insensible a la ca\u00edda masiva de los tipos de inter\u00e9s. As\u00ed que lo que tenemos es una situaci\u00f3n en la que cada vez m\u00e1s las empresas est\u00e1n rechazando m\u00e1s y m\u00e1s proyectos prospectivamente rentables. Y lo que estos economistas hicieron fue revisar las transcripciones de estas llamadas de ganancias, e hicieron una base de datos de lo que eran las tasas de rentabilidad de estas empresas. Los rastrearon en el tiempo. Y lo que encontraron, en primer lugar, es que, s\u00ed, ha habido una disminuci\u00f3n mucho menos que proporcional en la tasa cr\u00edtica de rentabilidad, de modo que a medida que el capital se ha abaratado, las empresas no han estado proporcionalmente m\u00e1s dispuestas a invertir.<\/p>\n\n\n\n<p>As\u00ed que plantearon la pregunta: \u00bfpor qu\u00e9? Y son un poco vagos a la hora de responder, pero tienen muy claro que de las transcripciones se desprende que los directores financieros creen que a los accionistas y a los gestores de activos les gusta que se abstengan de invertir en proyectos que son rentables pero no lo suficiente. Les gusta porque es una se\u00f1al. Indica que estos ejecutivos no est\u00e1n construyendo un imperio, derrochando dinero en proyectos grandiosos. Est\u00e1n devolviendo fondos a los propietarios de la corporaci\u00f3n, los accionistas \u2013 todo este tipo de ideolog\u00eda que ha impregnado los mercados financieros desde la d\u00e9cada de 1980. Doug escribi\u00f3 extensamente sobre ello en&nbsp;<em>Wall Street<\/em>.<\/p>\n\n\n\n<p>Y junto con la revoluci\u00f3n en la pol\u00edtica macroecon\u00f3mica, esta revoluci\u00f3n en las finanzas corporativas y la ideolog\u00eda de gesti\u00f3n que est\u00e1 incrustada en las estructuras institucionales de las empresas \u2013 creo que estas dos cosas probablemente pueden explicar conjuntamente la mayor\u00eda de los cambios que hemos visto, incluyendo la disminuci\u00f3n de las tasas de crecimiento agregado.<\/p>\n\n\n\n<p>Es una gran afirmaci\u00f3n. Pero se trata de grandes tendencias. Creo que este es otro ejemplo del importante papel del dinero y las finanzas. Hay una larga tradici\u00f3n en el marxismo de denigrar la importancia del dinero y las finanzas; tambi\u00e9n hay una tradici\u00f3n alternativa de hacer hincapi\u00e9 en que es importante. Pero la idea de que estos son rasgos superficiales de la econom\u00eda, y que la verdadera realidad subyacente es la morada de la producci\u00f3n, a menudo nos puede distraer de lo centralmente importante que es este tipo de cosas financieras. Esa ser\u00eda mi mejor conjetura sobre por qu\u00e9 la inversi\u00f3n ha sido m\u00e1s lenta de lo que cabr\u00eda esperar.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Perm\u00edtanme hacerles una \u00faltima pregunta. Siempre que hablo de crecimiento, recibo correos electr\u00f3nicos de gente que dice que el crecimiento nos est\u00e1 matando, que necesitamos decrecer. No estoy necesariamente de acuerdo con eso, pero es una cuesti\u00f3n de estos d\u00edas. Entonces, \u00bfpor qu\u00e9 debemos preocuparnos por el crecimiento? \u00bfEs algo que deber\u00edamos intentar superar?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>Mi idea de una especie de convergencia entre las teor\u00edas marxistas de la larga ola y las teor\u00edas del estancamiento secular me lleva definitivamente a tener un punto de vista que creo que el m\u00e1s radical de los keynesianos radicales mantendria y creo que el mejor de los marxistas tambi\u00e9n, y es que el objetivo no es simplemente desencadenar las fuerzas de producci\u00f3n e imaginar que debido a algun vicio en la forma en que los capitalistas toman las decisiones de inversi\u00f3n, una sociedad socialista simplemente ser\u00e1 capaz de lograr tasas de crecimiento inauditas y navegar hacia las estrellas.<\/p>\n\n\n\n<p>Creo que si le preguntaramos a Keynes o a William Beveridge cu\u00e1l es el objetivo de todo esto, el mejor marxista habr\u00eda dicho que deber\u00edamos hacer una \u00faltima gran construcci\u00f3n y que deber\u00eda tener un verdadero prop\u00f3sito p\u00fablico. Ya sabes, como dijo Beveridge, al igual que la guerra realmente inspir\u00f3 a la gente que estaba reci\u00e9n desempleada y deprimida a levantarse cada ma\u00f1ana y hacer algo para defender a sus familias, podr\u00edamos organizar proyectos p\u00fablicos \u2013 no para hacer la guerra a los extranjeros, sino m\u00e1s bien para hacer la guerra a la enfermedad, la ignorancia, la miseria y la pobreza.<\/p>\n\n\n\n<p>Y ese gran proyecto p\u00fablico de construir el equipamiento fijo, el equipamiento y las m\u00e1quinas que la humanidad necesita hoy, se parece a construir hospitales y escuelas y todo el resto de cosas que Beveridge tambi\u00e9n imagin\u00f3, con las que much\u00edsimas personas en el mundo est\u00e1n masivamente mal equipadas. Pero en nuestro tiempo, tambi\u00e9n significa una gran transici\u00f3n ecol\u00f3gica, un gran esfuerzo para sacarnos de los combustibles f\u00f3siles. Y creo que, hagamos lo que hagamos, tendr\u00eda que estar en consonancia con la ciencia. Y yo no soy cient\u00edfico. No tengo capacidad para juzgar cu\u00e1l es el camino adecuado hacia una econom\u00eda realmente sostenible. Y preferir\u00eda escuchar a la gente que sabe sobre eso; escucharlos, debatirlo, y que la gente decida sobre esa base.<\/p>\n\n\n\n<p>Pero estoy de acuerdo con Keynes y Marx y W. E. B. Du Bois y la Internacional de Trabajadores del Mundo (IWW) y todos los dem\u00e1s en que el objetivo a largo plazo es reducir la tasa de ahorro, reducir la inversi\u00f3n, aumentar el consumo de la clase trabajadora, y realmente llegar a un mundo donde haya una expectativa mucho menor de crecimiento para el futuro. Pero eso no significa un mundo sin dinamismo, verdadero dinamismo humano e innovaci\u00f3n en todo el amplio espectro de posibilidades humanas y no s\u00f3lo en la econom\u00eda. As\u00ed que creo que esa es una especie de versi\u00f3n racional de un futuro de decrecimiento, pero que requiere un \u00faltimo esfuerzo para elevar el nivel de vida de la humanidad en l\u00ednea con lo que es sostenible. Creo que ese debe ser el objetivo por el que luchemos.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Seth, \u00bfunas palabras para los decrecentistas?<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>Bueno, eso tiene mucho sentido para m\u00ed. Tambi\u00e9n se me ha ocurrido que hay un solapamiento entre este debate y el del decrecimiento, que tambi\u00e9n ha tenido lugar al mismo tiempo, en el sentido de que la naturaleza de lo que estamos hablando depende en gran medida de este constructo, el constructo estad\u00edstico del PIB. Siempre que hablamos de estancamiento o no estancamiento, no hay forma de hablar de ello de forma coherente sin utilizar alg\u00fan tipo de agregaci\u00f3n estad\u00edstica, porque obviamente cuando la econom\u00eda produce cosas, produce muchos tipos de cosas diferentes, muchos productos diferentes. \u00bfY c\u00f3mo se puede decir si hoy producimos m\u00e1s que el a\u00f1o pasado sin agregarlos de alguna manera? Y eso significa que tienes que sumar todos los valores monetarios, pero luego tienes que calcular cu\u00e1nta inflaci\u00f3n ha habido.<\/p>\n\n\n\n<p>Y todo esto lleva, por necesidad, a una enorme cantidad de conjeturas sobre cuestiones cualitativas relativas a productos y servicios y hasta qu\u00e9 punto deben contarse como indicadores de crecimiento cuantitativo. Una cosa es cuando se habla de un pa\u00eds pobre, pero cuando se habla de pa\u00edses en la frontera de la productividad, tengo la sensaci\u00f3n de que cada vez m\u00e1s se llega a un punto en el que las tasas de crecimiento de la productividad dependen de los juicios de los estad\u00edsticos de las agencias gubernamentales, que hacen el mejor trabajo que pueden, y hacen un buen trabajo. Pero en \u00faltima instancia, cada vez m\u00e1s, la cuesti\u00f3n de si estamos produciendo m\u00e1s, si la producci\u00f3n se est\u00e1 expandiendo y en qu\u00e9 medida, sospecho que si estamos juzgando eso por el tipo de criterios humanos que los tres pensamos que son importantes, las estad\u00edsticas oficiales importan cada vez menos, por lo que se vuelve cada vez menos crucial para lograr cualquier tasa de crecimiento en particular en los pa\u00edses donde el nivel ya es tan alto como lo es en los pa\u00edses ricos.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>Pero el problema es que el capitalismo no vive sist\u00e9micamente bien con tasas de crecimiento bajas necesariamente. \u00bfO no?<\/p>\n\n\n\n<p><strong>Seth Ackerman<\/strong><\/p>\n\n\n\n<p>Pues no lo s\u00e9. Si nos remontamos a 1970, mucha gente dec\u00eda que las tasas de crecimiento han sido realmente altas y que esto ha llevado a una revoluci\u00f3n de expectativas crecientes y a la masificaci\u00f3n de las ciudades, generando posibilidades revolucionarias. Ciertamente, si la inversi\u00f3n se detiene y no hay beneficios, algo se va a romper. Pero eso no est\u00e1 ocurriendo. Lo que est\u00e1 ocurriendo es que estas cosas est\u00e1n aumentando a un ritmo algo m\u00e1s lento.<\/p>\n\n\n\n<p><strong>Doug Henwood<\/strong><\/p>\n\n\n\n<p>\u00bfAlg\u00fan comentario al respecto, Aaron?<\/p>\n\n\n\n<p><strong>Aaron Benanav<\/strong><\/p>\n\n\n\n<p>A eso me refiero: el capitalismo tiene un gran problema con el crecimiento lento que tiene que ver con el car\u00e1cter de clase de la sociedad. La esperanza de la humanidad es la esperanza de una transici\u00f3n a una econom\u00eda de inversi\u00f3n p\u00fablica que haga la transici\u00f3n verde, que mida su \u00e9xito en estos t\u00e9rminos concretos, \u2013 no en t\u00e9rminos de crecimiento abstracto sino en la batalla real por mejorar las m\u00faltiples condiciones de la vida social. Pero creo que va a ser una gran lucha. Va a implicar romper realmente con las organizaciones que durante mucho tiempo han organizado la derrota de la clase obrera frente a la embestida capitalista. Y eso, de nuevo, nos ayuda a situarnos en el momento presente y a entender el car\u00e1cter de las luchas que est\u00e1n en marcha y que han ido en aumento en los \u00faltimos diez a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doug Henwood (Sin Permiso, 27-10-23) Un debate entre Seth Ackerman y Aaron Benanav sobre el pron\u00f3stico del capitalismo: \u00bfEst\u00e1 experimentando el tipo de estancamiento a largo plazo que muchos marxistas han considerado durante mucho tiempo como su destino? \u00bfQu\u00e9 significa esta respuesta para la estrategia pol\u00edtica socialista actual? Entrevista realizada por Doug Henwood. Durante las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,14],"tags":[],"class_list":["post-55065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-internacionales"],"_links":{"self":[{"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/posts\/55065"}],"collection":[{"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/comments?post=55065"}],"version-history":[{"count":1,"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/posts\/55065\/revisions"}],"predecessor-version":[{"id":55067,"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/posts\/55065\/revisions\/55067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/media\/55066"}],"wp:attachment":[{"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/media?parent=55065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/categories?post=55065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/debateplural.net\/site\/wp-json\/wp\/v2\/tags?post=55065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}